{"id":6469,"date":"2024-01-23T09:01:44","date_gmt":"2024-01-23T09:01:44","guid":{"rendered":"https:\/\/smartecarte.com\/john-f-kennedy-new\/"},"modified":"2024-03-12T09:51:50","modified_gmt":"2024-03-12T09:51:50","slug":"john-f-kennedy-new","status":"publish","type":"page","link":"https:\/\/smartecarte.com\/es\/john-f-kennedy-new\/","title":{"rendered":"John F. Kennedy NOVEDAD"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"6469\" class=\"elementor elementor-6469 elementor-6308\">\n\t\t\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-bf09200 elementor-section-full_width section-banner section-banner-inner elementor-section-height-default elementor-section-height-default\" data-id=\"bf09200\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-323d682a\" data-id=\"323d682a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1a044615 banner-text elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1a044615\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4e26b2d7\" data-id=\"4e26b2d7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f91780b elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"2f91780b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nueva York \u2013 John F. Kennedy (JFK)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8765594 elementor-widget elementor-widget-heading\" data-id=\"8765594\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Deja que Smarte Carte te ayude a hacer que tus viajes por el Aeropuerto John F. Kennedy (JFK) sean f\u00e1ciles y sin estr\u00e9s con nuestros servicios para pasajeros.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-18b46280 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"18b46280\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5e4904d7\" data-id=\"5e4904d7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a8197f2 inner-scroll elementor-widget elementor-widget-text-editor\" data-id=\"1a8197f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<a class=\"scroll-arrow\" href=\"\">\n<lottie-player src=\"\/wp-content\/themes\/smarte-carte\/images\/hero-arrow-animation.json\" background=\"transparent\" speed=\"1\" style=\"width: 42px; height: 68px;\" loop=\"\" autoplay=\"\"><\/lottie-player>\n<\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-33eb6890 airport-slider elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"33eb6890\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-57b8b919\" data-id=\"57b8b919\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5de5105a elementor-widget elementor-widget-heading\" data-id=\"5de5105a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Smarte Carte hace que viajar por el aeropuerto JFK sea una experiencia perfecta<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e5b3c1f home-slider elementor-widget elementor-widget-Vertical-Navigation\" data-id=\"e5b3c1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"Vertical-Navigation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t\n\n\t\t<div id=\"wcontainer\">\n\t\t\t<div id=\"pinContainer\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"slider-column\">\n\t\t\t\t\t<div class=\"tab-column\">\n\t\t\t\t\t\t<div class=\"vertical-tab\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slick-slide\">\n\t\t\t\t\t\t\t\t\t<h3>Almacenamiento de equipajes<\/h3>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slick-slide\">\n\t\t\t\t\t\t\t\t\t<h3>Recepci\u00f3n y bienvenida<\/h3>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slick-slide\">\n\t\t\t\t\t\t\t\t\t<h3>Objetos perdidos<\/h3>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slick-slide\">\n\t\t\t\t\t\t\t\t\t<h3>Servicio de portaequipajes<\/h3>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slick-slide\">\n\t\t\t\t\t\t\t\t\t<h3>Servicios de informaci\u00f3n<\/h3>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"tab-content-column\">\n\t\t\t\t\t\t<div class=\"vertical-tab-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slick-slide\">\n\t\t\t\t\t\t\t\t\t<figure>\n\t\t\t\t\t\t\t\t\t\t<div aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/06\/Airports_baggage-storage.jpg\" title=\"Airports_baggage-storage\" alt=\"Airports_baggage\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<figcaption>\n\t\t\t\t\t\t\t\t\t\t\t<div>\n\t\t\t\t\t\t\t\t\t\t\t\t<h3>Almacenamiento de equipajes<\/h3>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<p><p>Nuestros servicios de almacenamiento de equipajes son una forma r\u00e1pida, segura y f\u00e1cil de guardar tus pertenencias.<\/p><\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t<div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"btn-arrow\" href=\"#baggageStorage\" tabindex=\"0\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t Learn more\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"arrow\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"\/wp-content\/themes\/smarte-carte\/images\/arrow-right.png\" \/>\n\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<!-- <a href=\"\" class=\"btn-arrow\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"arrow\"><svg width=\"20\" height=\"20\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"m7.425 16.6 5.433-5.433a1.655 1.655 0 0 0 0-2.334L7.425 3.4\" stroke=\"#F7B93A\" stroke-width=\"1.5\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a> -->\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/figcaption>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slick-slide\">\n\t\t\t\t\t\t\t\t\t<figure>\n\t\t\t\t\t\t\t\t\t\t<div aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/Airports_meet-greet.jpg\" title=\"Airports_meet-greet\" alt=\"Airports_meet\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<figcaption>\n\t\t\t\t\t\t\t\t\t\t\t<div>\n\t\t\t\t\t\t\t\t\t\t\t\t<h3>Recepci\u00f3n y bienvenida<\/h3>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<p><p>Disfruta de una experiencia sin estr\u00e9s y sin problemas la pr\u00f3xima vez que pases por el aeropuerto con nuestro servicio de bienvenida.<\/p><\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t<div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"btn-arrow\" href=\"#meetAndGreat\" tabindex=\"0\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t Learn more\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"arrow\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"\/wp-content\/themes\/smarte-carte\/images\/arrow-right.png\" \/>\n\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<!-- <a href=\"\" class=\"btn-arrow\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"arrow\"><svg width=\"20\" height=\"20\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"m7.425 16.6 5.433-5.433a1.655 1.655 0 0 0 0-2.334L7.425 3.4\" stroke=\"#F7B93A\" stroke-width=\"1.5\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a> -->\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/figcaption>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slick-slide\">\n\t\t\t\t\t\t\t\t\t<figure>\n\t\t\t\t\t\t\t\t\t\t<div aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/Airports_lost-found.jpg\" title=\"Airports_lost-found\" alt=\"Airports_lost-found\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<figcaption>\n\t\t\t\t\t\t\t\t\t\t\t<div>\n\t\t\t\t\t\t\t\t\t\t\t\t<h3>Objetos perdidos<\/h3>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<p><p>Nuestros servicios de objetos perdidos pueden ayudarte a encontrar el art\u00edculo desaparecido. Nuestro proceso es r\u00e1pido y sencillo.<\/p><\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t<div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"btn-arrow\" href=\"#lostAndFound\" tabindex=\"0\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t Learn more\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"arrow\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"\/wp-content\/themes\/smarte-carte\/images\/arrow-right.png\" \/>\n\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<!-- <a href=\"\" class=\"btn-arrow\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"arrow\"><svg width=\"20\" height=\"20\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"m7.425 16.6 5.433-5.433a1.655 1.655 0 0 0 0-2.334L7.425 3.4\" stroke=\"#F7B93A\" stroke-width=\"1.5\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a> -->\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/figcaption>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slick-slide\">\n\t\t\t\t\t\t\t\t\t<figure>\n\t\t\t\t\t\t\t\t\t\t<div aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/06\/Img-6.jpg\" title=\"Img\" alt=\"Airport Services\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<figcaption>\n\t\t\t\t\t\t\t\t\t\t\t<div>\n\t\t\t\t\t\t\t\t\t\t\t\t<h3>Servicio de portaequipajes<\/h3>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<p><p>Nuestro equipo profesional de mozos de equipaje est\u00e1 aqu\u00ed para ayudarte a llevarte a ti y a tus maletas a donde necesites ir.<\/p><\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t<div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"btn-arrow\" href=\"#porterService\" tabindex=\"0\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t Learn more\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"arrow\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"\/wp-content\/themes\/smarte-carte\/images\/arrow-right.png\" \/>\n\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<!-- <a href=\"\" class=\"btn-arrow\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"arrow\"><svg width=\"20\" height=\"20\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"m7.425 16.6 5.433-5.433a1.655 1.655 0 0 0 0-2.334L7.425 3.4\" stroke=\"#F7B93A\" stroke-width=\"1.5\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a> -->\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/figcaption>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slick-slide\">\n\t\t\t\t\t\t\t\t\t<figure>\n\t\t\t\t\t\t\t\t\t\t<div aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/Airports_information-services-scaled.jpg\" title=\"Airports_information-services\" alt=\"Airports_information\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<figcaption>\n\t\t\t\t\t\t\t\t\t\t\t<div>\n\t\t\t\t\t\t\t\t\t\t\t\t<h3>Servicios de informaci\u00f3n<\/h3>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<p><p>\u00bfNecesita informaci\u00f3n sobre el aeropuerto? \u00bfSobre c\u00f3mo llegar a la puerta de embarque? Sean cuales sean tus preguntas, los miembros de nuestro equipo est\u00e1n a tu disposici\u00f3n para ayudarte.<\/p><\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t<div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"btn-arrow\" href=\"#informationService\" tabindex=\"0\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t Learn more\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"arrow\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"\/wp-content\/themes\/smarte-carte\/images\/arrow-right.png\" \/>\n\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<!-- <a href=\"\" class=\"btn-arrow\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"arrow\"><svg width=\"20\" height=\"20\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"m7.425 16.6 5.433-5.433a1.655 1.655 0 0 0 0-2.334L7.425 3.4\" stroke=\"#F7B93A\" stroke-width=\"1.5\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a> -->\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/figcaption>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\n\t\t\t<\/div>\n\n\t\t\t<script>\n\t\t\t\tjQuery(window).on('load', function () {\n\t\t\t\t\tconsole.log(\"1\");\n\t\t\t\t\t\/\/ Enhance ARIA after slick has initialized\n\t\t\t\t\tjQuery('.vertical-tab').on('init', function () {\n\t\t\t\t\t\tconsole.log(\"2\");\n\t\t\t\t\t\tenhanceSlickAria('.vertical-tab', '.vertical-tab-content');\n\t\t\t\t\t});\n\n\t\t\t\t\tjQuery('.vertical-tab-content').on('init', function () {\n\t\t\t\t\t\tconsole.log(\"3\");\n\t\t\t\t\t\tenhanceSlickAria('.vertical-tab', '.vertical-tab-content');\n\t\t\t\t\t});\n\t\t\t\t});\n\t\t\t\tvar slidecount = 5;\n\t\t\t\tif (slidecount < 10) {\n\t\t\t\t\tjQuery(window).load(function () {\n\t\t\t\t\t\t$('.vertical-tab').addClass('removerotation');\n\t\t\t\t\t\tlet tabcontent = jQuery('.vertical-tab-content').slick({\n\t\t\t\t\t\t\tvertical: true,\n\t\t\t\t\t\t\tarrows: false,\n\t\t\t\t\t\t\tdots: true,\n\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\tslidesToScroll: 1,\n\t\t\t\t\t\t\tasNavFor: '.vertical-tab',\n\t\t\t\t\t\t\tautoplaySpeed: 2000,\n\t\t\t\t\t\t\tautoplay: true,\n\t\t\t\t\t\t\tresponsive: [\n\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tbreakpoint: 991,\n\t\t\t\t\t\t\t\t\tsettings: {\n\t\t\t\t\t\t\t\t\t\tvertical: false,\n\t\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t],\n\t\t\t\t\t\t\tswipeToSlide: true,\n\t\t\t\t\t\t\tadaptiveHeight: true,\n\t\t\t\t\t\t\tuseCSS: true,\n\t\t\t\t\t\t\tonInit: function () {\n\t\t\t\t\t\t\t\t\/\/ Remove the role=\"button\" from slides after slick initialization\n\t\t\t\t\t\t\t\t$('.slick-slide').removeAttr('role');\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t}).on('init afterChange', function() {\n    $('.slick-slide').each(function() {\n      const $slide = $(this);\n      const isActive = $slide.hasClass('slick-active');\n      \n      \/\/ Update aria-hidden\n      $slide.attr('aria-hidden', !isActive);\n      \n      \/\/ Toggle tabindex for focusable elements\n      $slide.find('a, button, [tabindex]').attr('tabindex', isActive ? '0' : '-1');\n    });\n  });\n\t\t\t\t\t\tlet tabslider = jQuery('.vertical-tab').slick({\n\t\t\t\t\t\t\tvertical: true,\n\t\t\t\t\t\t\tarrows: false,\n\t\t\t\t\t\t\tinfinite: false,\n\t\t\t\t\t\t\tdots: false,\n\t\t\t\t\t\t\tslidesToShow: 6,\n\t\t\t\t\t\t\tautoplay: false,\n\t\t\t\t\t\t\tautoplaySpeed: 2000,\n\t\t\t\t\t\t\tasNavFor: '.vertical-tab-content',\n\t\t\t\t\t\t\tfocusOnSelect: true,\n\t\t\t\t\t\t\tonInit: function () {\n\t\t\t\t\t\t\t\t\/\/ Remove the role=\"button\" from slides after slick initialization\n\t\t\t\t\t\t\t\t$('.slick-slide').removeAttr('role');\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t});\n\t\t\t\t\t\t$('.vertical-tab').on('afterChange', function (event, slick, currentSlide) {\n\t\t\t\t\t\t\tconst $current = $(slick.$slides.get(currentSlide));\n\t\t\t\t\t\t\tconst text = $current.text().trim();\n\n\t\t\t\t\t\t\t\/\/ Update ARIA live region\n\t\t\t\t\t\t\t$('#live-region').text(text);\n\t\t\t\t\t\t});\n\t\t\t\t\t\t$('.vertical-tab-content').on('afterChange', function (event, slick, currentSlide) {\n\t\t\t\t\t\t\tconst $activeSlide = $(slick.$slides[currentSlide]);\n\n\t\t\t\t\t\t\t\/\/ Find first focusable element (adjust selector based on your content)\n\t\t\t\t\t\t\tconst $focusable = $activeSlide.find('a, button, [tabindex]:not([tabindex=\"-1\"]), h3, p').filter(':visible').first();\n\n\t\t\t\t\t\t\tif ($focusable.length) {\n\t\t\t\t\t\t\t\t$focusable.focus();\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t});\n\n\n\t\t\t\t\t\t\/\/ Set up the Intersection Observer\n\t\t\t\t\t\tconst observer = new IntersectionObserver((entries, observer) => {\n\t\t\t\t\t\t\tentries.forEach(entry => {\n\t\t\t\t\t\t\t\tif (entry.isIntersecting) {\n\t\t\t\t\t\t\t\t\t\/\/ When the carousel is in view, start autoplay\n\t\t\t\t\t\t\t\t\tjQuery('.vertical-tab').slick('slickPlay');\n\t\t\t\t\t\t\t\t} else {\n\t\t\t\t\t\t\t\t\t\/\/ When the carousel is out of view, stop autoplay\n\t\t\t\t\t\t\t\t\tjQuery('.vertical-tab').slick('slickPause');\n\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t});\n\t\t\t\t\t\t}, {\n\t\t\t\t\t\t\tthreshold: 0.5  \/\/ The percentage of the element that needs to be visible\n\t\t\t\t\t\t});\n\n\t\t\t\t\t\t\/\/ Observe the carousel element\n\t\t\t\t\t\tconst carouselElement = document.querySelector('.vertical-tab');\n\t\t\t\t\t\tobserver.observe(carouselElement);\n\t\t\t\t\t});\n\n\t\t\t\t}\n\t\t\t\telse {\n\t\t\t\t\tjQuery(window).load(function () {\n\n\n\t\t\t\t\t\tlet tabcontent = jQuery('.vertical-tab-content').slick({\n\t\t\t\t\t\t\tvertical: true,\n\t\t\t\t\t\t\tarrows: false,\n\t\t\t\t\t\t\tdots: true,\n\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\tslidesToScroll: 1,\n\t\t\t\t\t\t\tasNavFor: '.vertical-tab',\n\t\t\t\t\t\t\tautoplaySpeed: 3000,\n\t\t\t\t\t\t\tautoplay: false,\n\t\t\t\t\t\t\tfocusOnSelect: true,\n\t\t\t\t\t\t\tresponsive: [\n\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tbreakpoint: 991,\n\t\t\t\t\t\t\t\t\tsettings: {\n\t\t\t\t\t\t\t\t\t\tvertical: false,\n\t\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t],\n\t\t\t\t\t\t\tonInit: function () {\n\t\t\t\t\t\t\t\t\/\/ Remove the role=\"button\" from slides after slick initialization\n\t\t\t\t\t\t\t\t$('.slick-slide').removeAttr('role');\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t}).on('init afterChange', function() {\n    $('.slick-slide').each(function() {\n      const $slide = $(this);\n      const isActive = $slide.hasClass('slick-active');\n      \n      \/\/ Update aria-hidden\n      $slide.attr('aria-hidden', !isActive);\n      \n      \/\/ Toggle tabindex for focusable elements\n      $slide.find('a, button, [tabindex]').attr('tabindex', isActive ? '0' : '-1');\n    });\n  });\n\t\t\t\t\t\tlet tabslider = jQuery('.vertical-tab').slick({\n\t\t\t\t\t\t\tdots: false,\n\t\t\t\t\t\t\tvertical: true,\n\t\t\t\t\t\t\tarrows: false,\n\t\t\t\t\t\t\tslidesToShow: 5,\n\t\t\t\t\t\t\tslidesToScroll: 1,\n\t\t\t\t\t\t\tverticalSwiping: true,\n\t\t\t\t\t\t\tinfinite: true,\n\t\t\t\t\t\t\tautoplay: false,\n\t\t\t\t\t\t\tautoplaySpeed: 3000,\n\t\t\t\t\t\t\tasNavFor: '.vertical-tab-content',\n\t\t\t\t\t\t\tfocusOnSelect: true,\n\t\t\t\t\t\t\tonInit: function () {\n\t\t\t\t\t\t\t\t\/\/ Remove the role=\"button\" from slides after slick initialization\n\t\t\t\t\t\t\t\t$('.slick-slide').removeAttr('role');\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t});\n\t\t\t\t\t\t\/\/ Get text from content slider when tab (nav) changes\n\t\t\t\t\t\tjQuery('.vertical-tab').on('afterChange', function (event, slick, currentSlide) {\n\t\t\t\t\t\t\tconst $contentSlides = jQuery('.vertical-tab-content').slick('getSlick').$slides;\n\t\t\t\t\t\t\tconst $currentContentSlide = jQuery($contentSlides.get(currentSlide));\n\t\t\t\t\t\t\tconst text = $currentContentSlide.text().trim();\n\n\t\t\t\t\t\t\t\/\/ Announce using live region\n\t\t\t\t\t\t\tjQuery('#live-region').text('');\n\t\t\t\t\t\t\tsetTimeout(() => {\n\t\t\t\t\t\t\t\tjQuery('#live-region').text(text);\n\t\t\t\t\t\t\t}, 100);\n\t\t\t\t\t\t});\n\t\t\t\t\t\t$('.vertical-tab').on('init', function () {\n\t\t\t\t\t\t\t$('.vertical-tab .slick-slide').removeAttr('role');\n\t\t\t\t\t\t});\n\n\t\t\t\t\t\t\/\/ Set up the Intersection Observer\n\t\t\t\t\t\tconst observer = new IntersectionObserver((entries, observer) => {\n\t\t\t\t\t\t\tentries.forEach(entry => {\n\t\t\t\t\t\t\t\tif (entry.isIntersecting) {\n\t\t\t\t\t\t\t\t\t\/\/ When the carousel is in view, start autoplay\n\t\t\t\t\t\t\t\t\tjQuery('.vertical-tab').slick('slickPlay');\n\t\t\t\t\t\t\t\t} else {\n\t\t\t\t\t\t\t\t\t\/\/ When the carousel is out of view, stop autoplay\n\t\t\t\t\t\t\t\t\tjQuery('.vertical-tab').slick('slickPause');\n\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t});\n\t\t\t\t\t\t}, {\n\t\t\t\t\t\t\tthreshold: 0.5  \/\/ The percentage of the element that needs to be visible\n\t\t\t\t\t\t});\n\n\t\t\t\t\t\t\/\/ Observe the carousel element\n\t\t\t\t\t\tconst carouselElement = document.querySelector('.vertical-tab');\n\t\t\t\t\t\tobserver.observe(carouselElement);\n\t\t\t\t\t});\n\t\t\t\t}\n\n\t\t\t\t\/\/ Accessibility Enhancements for Slick Tabs\n\t\t\t\tfunction enhanceSlickAria(tabSelector, contentSelector) {\n    const $tab = jQuery(tabSelector);\n    const $content = jQuery(contentSelector);\n\n    \/\/ Initialize tablist\n    $tab.attr({\n        'role': 'tablist',\n        'aria-label': 'Markets Navigation'\n    });\n\n    \/\/ Process tabs\n    $tab.find('.slick-slide').each(function(index) {\n        const $this = jQuery(this);\n        const tabId = 'custom-tab-' + index;\n        const panelId = 'custom-panel-' + index;\n        const slideLabel = $this.attr('aria-label') || 'Slide ' + (index + 1);\n        \n        \/\/ Ensure tab has text content for screen readers\n        if (!$this.text().trim()) {\n            $this.html('<span class=\"sr-only\">' + slideLabel + '<\/span>');\n        }\n\n        $this.attr({\n            'role': 'tab',\n            'id': tabId,\n            'aria-controls': panelId,\n            'aria-selected': index === 0 ? 'true' : 'false',\n            'tabindex': index === 0 ? '0' : '-1'\n        });\n    });\n\n    \/\/ Process panels\n    $content.find('.slick-slide').each(function(index) {\n        const $this = jQuery(this);\n        const tabId = 'custom-tab-' + index;\n        const panelId = 'custom-panel-' + index;\n        \n        \/\/ Find or create a heading for the panel\n        let $heading = $this.find('h2, h3, h4').first();\n        if (!$heading.length) {\n            $heading = $this.find('figure').first().prev('h2, h3, h4');\n        }\n        \n        \/\/ If no heading exists, create one from the tab's label\n        if (!$heading.length) {\n            const tabLabel = jQuery('#' + tabId).attr('aria-label') || 'Slide ' + (index + 1);\n            $heading = jQuery('<h3 class=\"sr-only\"><\/h3>').text(tabLabel).prependTo($this);\n        }\n        \n        \/\/ Ensure heading has an ID\n        const headingId = 'panel-heading-' + index;\n        $heading.attr('id', headingId);\n\n        $this.attr({\n            'role': 'tabpanel',\n            'id': panelId,\n            'aria-labelledby': headingId, \/\/ Use the heading instead of tab reference\n            'aria-hidden': index === 0 ? 'false' : 'true',\n            'tabindex': '0' \/\/ All panels should be tabbable when visible\n        });\n    });\n\n    \/\/ Handle slide changes\n    $tab.on('afterChange', function(event, slick, currentSlide) {\n        \/\/ Update tabs\n        $tab.find('.slick-slide').each(function(index) {\n            jQuery(this).attr({\n                'aria-selected': index === currentSlide ? 'true' : 'false',\n                'tabindex': index === currentSlide ? '0' : '-1'\n            });\n        });\n\n        \/\/ Update panels\n        $content.find('.slick-slide').each(function(index) {\n            jQuery(this).attr({\n                'aria-hidden': index === currentSlide ? 'false' : 'true'\n            });\n        });\n    });\n}\n\t\t\t\t\n\n\n\t\t\t<\/script>\n\n\n\t\t\t<script>\n\t\t\t\t\t\t\t\tvar temp = [\"#Almacenamiento-de-equipajes\",\"#Recepci\\u00f3n-y-bienvenida\",\"#Objetos-perdidos\",\"#Servicio-de-portaequipajes\",\"#Servicios-de-informaci\\u00f3n\"];\n\t\t\t\tvar panels = [{\"trigger\":\"#Recepci\\u00f3n-y-bienvenida\",\"name\":\".epanel1\"},{\"trigger\":\"#Objetos-perdidos\",\"name\":\".epanel2\"},{\"trigger\":\"#Servicio-de-portaequipajes\",\"name\":\".epanel3\"},{\"trigger\":\"#Servicios-de-informaci\\u00f3n\",\"name\":\".epanel4\"}];\n\t\t\t<\/script>\n\t\t\t\t\t<\/div>\n\n\n\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1aaf676c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1aaf676c\" data-element_type=\"section\" data-e-type=\"section\" id=\"porterService\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4198c6ef porter-service\" data-id=\"4198c6ef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77fc9f64 elementor-widget elementor-widget-heading\" data-id=\"77fc9f64\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Servicio de portaequipajes<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d0ea79d calibri-regular elementor-widget elementor-widget-text-editor\" data-id=\"4d0ea79d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Experimenta un viaje sin complicaciones con nuestro equipo de portaequipajes profesionales. Cuenta con nosotros para<br>desplazarte con tu equipaje de forma eficiente, al ofrecerte precios transparentes y opciones de pago flexibles, tales como<br>\ntarjetas de cr\u00e9dito, pagos con dispositivos m\u00f3viles y efectivo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4051110d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4051110d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6c987694 porter-img\" data-id=\"6c987694\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65a8b19d elementor-widget elementor-widget-image\" data-id=\"65a8b19d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1708\" height=\"2560\" src=\"https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/SmarteCarte_JFK_8488-final-scaled.jpg\" class=\"attachment-full size-full wp-image-4069\" alt=\"\" srcset=\"https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/SmarteCarte_JFK_8488-final-scaled.jpg 1708w, https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/SmarteCarte_JFK_8488-final-200x300.jpg 200w, https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/SmarteCarte_JFK_8488-final-683x1024.jpg 683w, https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/SmarteCarte_JFK_8488-final-768x1151.jpg 768w, https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/SmarteCarte_JFK_8488-final-1025x1536.jpg 1025w, https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/SmarteCarte_JFK_8488-final-1366x2048.jpg 1366w\" sizes=\"(max-width: 1708px) 100vw, 1708px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7525c258\" data-id=\"7525c258\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-575ae46b elementor-widget elementor-widget-text-editor\" data-id=\"575ae46b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<span>VUELOS DE SALIDA<\/span><label>:<\/label>B\u00fascanos en la acera. Nuestros portaequipajes te ayudar\u00e1n\na transportar tu equipaje desde la acera hasta\nlos mostradores de facturaci\u00f3n de las aerol\u00edneas.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ec4864 elementor-widget elementor-widget-text-editor\" data-id=\"3ec4864\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<span>VUELOS DE LLEGADA<\/span><label>:<\/label> B\u00fascanos junto a la cinta transportadora de equipajes. Nuestros portaequipajes recoger\u00e1n\ntu equipaje desde la cinta transportadora de equipajes y lo llevar\u00e1n a tu\nmodo de transporte elegido.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-25d53e1d baggage elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"25d53e1d\" data-element_type=\"section\" data-e-type=\"section\" id=\"baggageStorage\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3e3f78a2\" data-id=\"3e3f78a2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-142d5a7f elementor-widget elementor-widget-heading\" data-id=\"142d5a7f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Almacenamiento de equipajes<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ae61bdc elementor-widget elementor-widget-heading\" data-id=\"1ae61bdc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Grande o peque\u00f1o, lo almacenamos todo.<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-641578dc calibri-regular elementor-widget elementor-widget-text-editor\" data-id=\"641578dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default elementor-inline-editing pen\" contenteditable=\"true\" data-elementor-setting-key=\"title\" data-pen-placeholder=\"Type Here...\">El almacenamiento de equipajes de Smarte Carte est\u00e1 especializado en proporcionar soluciones de almacenamiento a corto y largo plazo. Tanto<br \/>si te diriges a la ciudad para hacer una visita r\u00e1pida como si necesitas una soluci\u00f3n fiable para un almacenamiento prolongado, conf\u00eda en nosotros para<br \/>mantener tus pertenencias a salvo y disponibles.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5cf78adb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5cf78adb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d913fe2 baggage-storage\" data-id=\"d913fe2\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6cf877b9 jfk-img1 elementor-widget elementor-widget-image\" data-id=\"6cf877b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"640\" height=\"591\" src=\"https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/12\/Rectangle-40353-1024x945.jpg\" class=\"attachment-large size-large wp-image-6110\" alt=\"smartecarte\" srcset=\"https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/12\/Rectangle-40353-1024x945.jpg 1024w, https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/12\/Rectangle-40353-300x277.jpg 300w, https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/12\/Rectangle-40353-768x709.jpg 768w, https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/12\/Rectangle-40353.jpg 1034w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1bcf84aa\" data-id=\"1bcf84aa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5c021395 elementor-widget elementor-widget-heading\" data-id=\"5c021395\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Terminal 1<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d395c9 calibri-regular elementor-widget elementor-widget-text-editor\" data-id=\"5d395c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Abierto todos los d\u00edas \/ de 7:00 a 22:00 EST<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed36596 airport-button learn-more-btn mb elementor-widget elementor-widget-html\" data-id=\"ed36596\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<a target=\"_blank\" style=\" background: #F7B93A!important; \" target=\"_blank\" onmouseenter=\"player61.play()\" onmouseleave=\"player61.stop()\" class=\"products-link bs-btn\" href=\"https:\/\/app.squarespacescheduling.com\/schedule.php?owner=27798654\">Reservar ahora en Terminal 1\n<lottie-player style=\" filter: brightness(0); \" id=\"player61\" src=\"\/wp-content\/themes\/smarte-carte\/images\/side-arrow-animation.json\" background=\"transparent\" speed=\"1\"><\/lottie-player><\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3fcc4e9c elementor-widget elementor-widget-heading\" data-id=\"3fcc4e9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Terminal 4<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f36916 calibri-regular elementor-widget elementor-widget-text-editor\" data-id=\"4f36916\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Abierto todos los d\u00edas las 24 horas<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a63a021 airport-button learn-more-btn mb elementor-widget elementor-widget-html\" data-id=\"a63a021\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<a target=\"_blank\" style=\" background: #F7B93A!important; target=\"_blank\" onmouseenter=\"player63.play()\" onmouseleave=\"player63.stop()\" class=\"products-link bs-btn\" href=\"https:\/\/app.squarespacescheduling.com\/schedule.php?owner=27702787\">Reservar ahora en Terminal 4\n<lottie-player style=\" filter: brightness(0); \" id=\"player63\" src=\"\/wp-content\/themes\/smarte-carte\/images\/side-arrow-animation.json\" background=\"transparent\" speed=\"1\"><\/lottie-player>\n<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e21ab51 elementor-widget elementor-widget-heading\" data-id=\"e21ab51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Terminal 7<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec91b94 calibri-regular elementor-widget elementor-widget-text-editor\" data-id=\"ec91b94\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Abierto todos los d\u00edas \/ de 6:00 a 00:00<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-70d6cf6 airport-button learn-more-btn mb elementor-widget elementor-widget-html\" data-id=\"70d6cf6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<a target=\"_blank\" style=\" background: #F7B93A!important; target=\"_blank\" onmouseenter=\"player62.play()\" onmouseleave=\"player62.stop()\" class=\"products-link bs-btn\" href=\"https:\/\/JFKTerminal7BaggageStorage.as.me\/\">Reservar ahora en Terminal 7\n<lottie-player style=\" filter: brightness(0); \" id=\"player62\" src=\"\/wp-content\/themes\/smarte-carte\/images\/side-arrow-animation.json\" background=\"transparent\" speed=\"1\"><\/lottie-player>\n<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-146fd9b8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"146fd9b8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-af0dca6\" data-id=\"af0dca6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7de83e3a calibri-regular elementor-widget elementor-widget-heading\" data-id=\"7de83e3a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Tambi\u00e9n tenemos art\u00edculos adicionales disponibles para comprarlos en la tienda de almacenamiento de equipaje <br>\nen la Terminal 1 y la Terminal 4, entre los que se incluyen: <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-176d72bd cali-font baggage-list elementor-icon-list--layout-inline elementor-align-center elementor-mobile-align-start elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"176d72bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"32\" height=\"32\" fill=\"none\" viewBox=\"0 0 32 32\"><rect width=\"32\" height=\"32\" rx=\"16\" fill=\"#F7B93A\"><\/rect><path d=\"M9 16c-.612.33-1 .5-1 1s3.6 6.1 4 6.5c.5.5 1 .5 2.5.5s4.5-5.5 5-6.5c.501-1.002 4-8 4-8.5s-2.5 0-3 .5c-.4.4-3.5 8-6 11.5-.5 0-1-1.5-1.5-2-.774-.775-1.5-3-2-3.5-.332-.332-1.388.17-2 .5Z\" fill=\"#000\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Cajas<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"32\" height=\"32\" fill=\"none\" viewBox=\"0 0 32 32\"><rect width=\"32\" height=\"32\" rx=\"16\" fill=\"#F7B93A\"><\/rect><path d=\"M9 16c-.612.33-1 .5-1 1s3.6 6.1 4 6.5c.5.5 1 .5 2.5.5s4.5-5.5 5-6.5c.501-1.002 4-8 4-8.5s-2.5 0-3 .5c-.4.4-3.5 8-6 11.5-.5 0-1-1.5-1.5-2-.774-.775-1.5-3-2-3.5-.332-.332-1.388.17-2 .5Z\" fill=\"#000\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Cintas<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"32\" height=\"32\" fill=\"none\" viewBox=\"0 0 32 32\"><rect width=\"32\" height=\"32\" rx=\"16\" fill=\"#F7B93A\"><\/rect><path d=\"M9 16c-.612.33-1 .5-1 1s3.6 6.1 4 6.5c.5.5 1 .5 2.5.5s4.5-5.5 5-6.5c.501-1.002 4-8 4-8.5s-2.5 0-3 .5c-.4.4-3.5 8-6 11.5-.5 0-1-1.5-1.5-2-.774-.775-1.5-3-2-3.5-.332-.332-1.388.17-2 .5Z\" fill=\"#000\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Bolsas<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"32\" height=\"32\" fill=\"none\" viewBox=\"0 0 32 32\"><rect width=\"32\" height=\"32\" rx=\"16\" fill=\"#F7B93A\"><\/rect><path d=\"M9 16c-.612.33-1 .5-1 1s3.6 6.1 4 6.5c.5.5 1 .5 2.5.5s4.5-5.5 5-6.5c.501-1.002 4-8 4-8.5s-2.5 0-3 .5c-.4.4-3.5 8-6 11.5-.5 0-1-1.5-1.5-2-.774-.775-1.5-3-2-3.5-.332-.332-1.388.17-2 .5Z\" fill=\"#000\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Envoltorio de burbujas<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"32\" height=\"32\" fill=\"none\" viewBox=\"0 0 32 32\"><rect width=\"32\" height=\"32\" rx=\"16\" fill=\"#F7B93A\"><\/rect><path d=\"M9 16c-.612.33-1 .5-1 1s3.6 6.1 4 6.5c.5.5 1 .5 2.5.5s4.5-5.5 5-6.5c.501-1.002 4-8 4-8.5s-2.5 0-3 .5c-.4.4-3.5 8-6 11.5-.5 0-1-1.5-1.5-2-.774-.775-1.5-3-2-3.5-.332-.332-1.388.17-2 .5Z\" fill=\"#000\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Candados<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"32\" height=\"32\" fill=\"none\" viewBox=\"0 0 32 32\"><rect width=\"32\" height=\"32\" rx=\"16\" fill=\"#F7B93A\"><\/rect><path d=\"M9 16c-.612.33-1 .5-1 1s3.6 6.1 4 6.5c.5.5 1 .5 2.5.5s4.5-5.5 5-6.5c.501-1.002 4-8 4-8.5s-2.5 0-3 .5c-.4.4-3.5 8-6 11.5-.5 0-1-1.5-1.5-2-.774-.775-1.5-3-2-3.5-.332-.332-1.388.17-2 .5Z\" fill=\"#000\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Embalaje de maletas<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9e2e6e elementor-widget elementor-widget-text-editor\" data-id=\"d9e2e6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<input id=\"state\" hidden=\"\" type=\"checkbox\" \/>\n<label for=\"state\">\n<div class=\"button-select\">Selecciona un servicio<\/div>\n<\/label>\n<div class=\"content-select\">\n\t<div class=\"inner-select\">\n\t\t<div class=\"jfk-service-outer\">\n\t\t\t<div class=\"jfk-service-item\">\n\n\t\t\t\t<img decoding=\"async\" class=\"alignnone size-full wp-image-2482\" src=\"https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/08\/JFK_Pricing-graphic_1-1.png\" alt=\"\" width=\"1114\" height=\"835\" srcset=\"https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/08\/JFK_Pricing-graphic_1-1.png 1114w, https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/08\/JFK_Pricing-graphic_1-1-300x225.png 300w, https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/08\/JFK_Pricing-graphic_1-1-1024x768.png 1024w, https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/08\/JFK_Pricing-graphic_1-1-768x576.png 768w\" sizes=\"(max-width: 1114px) 100vw, 1114px\" \/>\n\t\t\t\t<h4>25\u00a0$<\/h4>\n\t\t\t<\/div>\n\t\t\t<div class=\"jfk-service-item\">\n\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2483\" src=\"https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/08\/JFK_Pricing-graphic_2-1.png\" alt=\"\" width=\"1019\" height=\"1045\" srcset=\"https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/08\/JFK_Pricing-graphic_2-1.png 1019w, https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/08\/JFK_Pricing-graphic_2-1-293x300.png 293w, https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/08\/JFK_Pricing-graphic_2-1-999x1024.png 999w, https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/08\/JFK_Pricing-graphic_2-1-768x788.png 768w\" sizes=\"(max-width: 1019px) 100vw, 1019px\" \/>\n\t\t\t\t<h4>35\u00a0$<\/h4>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"jfk-service-outer listitems\">\n\t\t\t<div class=\"jfk-service-item\">\n\t\t\t\t<ul>\n\t\t\t\t\t<li>Los precios son por art\u00edculo; por ciclo de 24 horas\n\t\t\t\t\t<\/li><li>Todas las maletas deben estar bloqueadas\n\t\t\t\t\t<\/li><li>Se requiere el pago completo en el momento de la entrega<\/li>\n\t\t\t\t<\/ul>\n\t\t\t<\/div>\n\t\t\t<div class=\"jfk-service-item\">\n\t\t\t\t<ul>\n\t\t\t\t\t<li>Se requiere una identificaci\u00f3n con foto y la tarjeta de embarque<\/li>\n\t\t\t\t\t<li>Est\u00e1n prohibidos los materiales inflamables, el alcohol, las armas de fuego,\n\t\t\t\ty los productos perecederos.<\/li>\n\t\t\t\t<\/ul>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48e42147 elementor-widget elementor-widget-heading\" data-id=\"48e42147\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00bfALGUNA PREGUNTA?&nbsp;<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5809f82f elementor-section-content-middle baggage-contact elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5809f82f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-32daca93 airport-phone\" data-id=\"32daca93\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6f84ef28 airport-button elementor-widget elementor-widget-html\" data-id=\"6f84ef28\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"single-location\">\n<div class=\"loc-icons\">\n<div class=\"loc-icons-item\"><img decoding=\"async\" src=\"https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/05\/phone.svg\" \/>\u00a0<a href=\"tel:718-916-8963\">718-916-8963<\/a><\/div>\n<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ebbdd1f airport-phone\" data-id=\"ebbdd1f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-72f5b5fb airport-button elementor-widget-mobile__width-initial elementor-widget elementor-widget-html\" data-id=\"72f5b5fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<a onmouseenter=\"question2.play()\" onmouseleave=\"question2.stop()\" class=\"products-link\" href=\"https:\/\/smartecarte.com\/contact\/\" data-toggle=\"modal\" data-target=\"#baggageModal\">CONTACTA CON NOSOTROS\n<lottie-player id=\"question2\" src=\"\/wp-content\/themes\/smarte-carte\/images\/side-arrow-animation.json\" background=\"transparent\" speed=\"1\"><\/lottie-player>\n<\/a>\n\n<div class=\"modal fade airport-popup \" id=\"baggageModal\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"baggageModal\" aria-hidden=\"true\">\n  <div class=\"modal-dialog\">\n    <div class=\"modal-content\">\n      <div class=\"modal-header\">\n        <h4 class=\"modal-title\" id=\"myModalLabel\">Contacta con nosotros<\/h4>\n        <button type=\"button\" class=\"close\" data-dismiss=\"modal\" aria-label=\"Close\">\n          <span aria-hidden=\"true\">&horarios;<\/span>\n        <\/button>\n      <\/div>\n      <div class=\"modal-body\">\n        <script charset=\"utf-8\" type=\"text\/javascript\" src=\"\/\/js.hsforms.net\/forms\/embed\/v2.js\"><\/script>\n<script>\n  hbspt.forms.create({\n    region: \"na1\",\n    portalId: \"5752400\",\n    formId: \"7ded5060-afdc-436d-a9a8-057dcc0f1e0c\"\n  });\n<\/script>\n      <\/div>\n    <\/div>\n  <\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-701e6a39 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"701e6a39\" data-element_type=\"section\" data-e-type=\"section\" id=\"meetAndGreat\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5ac55815\" data-id=\"5ac55815\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f635dfb elementor-widget elementor-widget-heading\" data-id=\"1f635dfb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Recepci\u00f3n y bienvenida<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2f7a0f9f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2f7a0f9f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7912c212\" data-id=\"7912c212\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5b427d2 elementor-widget elementor-widget-image\" data-id=\"5b427d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"363\" src=\"https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/SmarteCarte_JFK_8533-final-1024x581.jpg\" class=\"attachment-large size-large wp-image-4071\" alt=\"\" srcset=\"https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/SmarteCarte_JFK_8533-final-1024x581.jpg 1024w, https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/SmarteCarte_JFK_8533-final-300x170.jpg 300w, https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/SmarteCarte_JFK_8533-final-768x436.jpg 768w, https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/SmarteCarte_JFK_8533-final-1536x872.jpg 1536w, https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/SmarteCarte_JFK_8533-final-2048x1162.jpg 2048w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-465aaff5 assistance\" data-id=\"465aaff5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-546a997f calibri-regular elementor-widget elementor-widget-text-editor\" data-id=\"546a997f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Experimenta la comodidad definitiva con nuestro servicio de reuni\u00f3n y bienvenida en la<br \/>Terminal 4, dise\u00f1ado para hacer que tu viaje sea fluido y agradable.<br \/> Tanto si te diriges a tu destino, como si viajas de regreso o te trasladas, nuestro amable<br \/>y profesional equipo te proporcionar\u00e1 un servicio personalizado de 2 horas.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-41a3cca7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"41a3cca7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-777e1118 flights\" data-id=\"777e1118\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ede0eff elementor-widget elementor-widget-heading\" data-id=\"1ede0eff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Vuelos de llegada<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-427fd2d0 elementor-align-start flight-list elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"427fd2d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Nacionales: saludo en la puerta con una tarjeta de lugar digital que muestra el nombre del cliente<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Internacionales: saludo en la recogida de equipajes con una tarjeta digital que muestra el nombre del cliente<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Asistencia de equipajes<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Acompa\u00f1amiento al punto de recogida del transporte, a la terminal de transferencias o al centro de alquiler de coches<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Seguimiento de los vuelos y asistencia en el embarque<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-038dd92 elementor-hidden-tablet elementor-hidden-mobile\" data-id=\"038dd92\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f087483 learn-more-btn t-align elementor-widget elementor-widget-html\" data-id=\"f087483\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a style=\" background: #F7B93A!important;\" onmouseenter=\"player621.play()\" onmouseleave=\"player621.stop()\" href=https:\/\/app.acuityscheduling.com\/schedule.php?owner=31000089 target=\"_blank\" class=\"products-link acuity-embed-button\">Reservar ahora <lottie-player style=\" filter: brightness(0); \" id=\"player621\" src=\"\/wp-content\/themes\/smarte-carte\/images\/side-arrow-animation.json\" background=\"transparent\" speed=\"1\"><\/lottie-player><\/a><link rel=\"stylesheet\" href=https:\/\/embed.acuityscheduling.com\/embed\/button\/31000089.css id=\"acuity-button-styles\" \/><script src=https:\/\/embed.acuityscheduling.com\/embed\/button\/31000089.js async><\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7cf4db67 flights\" data-id=\"7cf4db67\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-730638a0 elementor-widget elementor-widget-heading\" data-id=\"730638a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Vuelos de salida<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ba2aa82 elementor-align-start flight-list elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2ba2aa82\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Saludo en la acera con una tarjeta digital que muestra el nombre del cliente<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Asistencia de equipajes<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Acompa\u00f1amiento a trav\u00e9s del check-in y el punto de control de seguridad (seg\u00fan el estado del cliente)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Acompa\u00f1amiento a salas o puertas de embarque<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Seguimiento de los vuelos y asistencia en el embarque<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cb77d01 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cb77d01\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-d79eb0d\" data-id=\"d79eb0d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5208fe1 learn-more-btn t-align elementor-hidden-desktop elementor-hidden-tablet_extra elementor-widget elementor-widget-html\" data-id=\"5208fe1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a href=https:\/\/app.acuityscheduling.com\/schedule.php?owner=31000089 target=\"_blank\" class=\"products-link acuity-embed-button\">Reservar ahora<\/a><link rel=\"stylesheet\" href=https:\/\/embed.acuityscheduling.com\/embed\/button\/31000089.css id=\"acuity-button-styles\" \/><script src=https:\/\/embed.acuityscheduling.com\/embed\/button\/31000089.js async><\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e7ca5e elementor-widget elementor-widget-heading\" data-id=\"8e7ca5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00bfALGUNA PREGUNTA?&nbsp;<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f427195 airport-button elementor-widget elementor-widget-html\" data-id=\"f427195\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"greet-phone single-location\" style=\"text-align:center\">\n<div class=\"loc-icons\">\n<div class=\"loc-icons-item\"><img decoding=\"async\" src=\"https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/05\/phone.svg\" \/>\u00a0<a href=\"tel:929-789-4151\">929-789-4151<\/a><\/div>\n<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9eb4b10 airport-button  elementor-widget-mobile__width-initial elementor-widget elementor-widget-html\" data-id=\"9eb4b10\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"bag-contact\">\n<p>\u00bfNecesitas asistencia en menos de 24 horas?<\/p><a onmouseenter=\"flights1.play()\" onmouseleave=\"flights1.stop()\" class=\"products-link\" data-toggle=\"modal\" data-target=\"#meetModal\">CONTACTA CON NOSOTROS\n<lottie-player id=\"flights1\" src=\"\/wp-content\/themes\/smarte-carte\/images\/side-arrow-animation.json\" background=\"transparent\" speed=\"1\"><\/lottie-player>\n<\/a><\/div>\n\n\n\n\n<div class=\"modal fade airport-popup \" id=\"meetModal\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"meetModal\" aria-hidden=\"true\">\n  <div class=\"modal-dialog\">\n    <div class=\"modal-content\">\n      <div class=\"modal-header\">\n        <h4 class=\"modal-title\" id=\"meetModalLabel\">Contacta con nosotros<\/h4>\n        <button type=\"button\" class=\"close\" data-dismiss=\"modal\" aria-label=\"Close\">\n          <span aria-hidden=\"true\">&horarios;<\/span>\n        <\/button>\n      <\/div>\n      <div class=\"modal-body\">\n        <script charset=\"utf-8\" type=\"text\/javascript\" src=\"\/\/js.hsforms.net\/forms\/embed\/v2.js\"><\/script>\n<script>\n  hbspt.forms.create({\n    region: \"na1\",\n    portalId: \"5752400\",\n    formId: \"2dc857a9-245d-4b35-b211-7765e1823b4f\"\n  });\n<\/script>\n      <\/div>\n    <\/div>\n  <\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-41d758f9 lost-found elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"41d758f9\" data-element_type=\"section\" data-e-type=\"section\" id=\"lostAndFound\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-34d50aef\" data-id=\"34d50aef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-760e90e2 elementor-widget elementor-widget-heading\" data-id=\"760e90e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Objetos perdidos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-42b17f73 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"42b17f73\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-315bd09\" data-id=\"315bd09\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d6de17 elementor-widget elementor-widget-heading\" data-id=\"0d6de17\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Terminal 4<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e9cf91 calibri-regular elementor-widget elementor-widget-text-editor\" data-id=\"8e9cf91\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>HORARIO DE SERVICIO<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e1f216c elementor-widget elementor-widget-heading\" data-id=\"6e1f216c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Abierto todos los d\u00edas las 24 horas<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5293e98 elementor-widget elementor-widget-text-editor\" data-id=\"5293e98\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"jfk-laf\">\n<div class=\"jfk-laf-item\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6051\" src=\"https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/12\/phone-1.svg\" alt=\"\" width=\"24\" height=\"24\" \/>+1 718-916-8963 <\/div>\n<div class=\"jfk-laf-item\"><img decoding=\"async\" src=\"https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/05\/marker.svg\" \/>John F. Kennedy Airport Jamaica, New York 11430 Terminal 4 Arrivals Ground Level<\/div>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf7b01a calibri-regular elementor-widget elementor-widget-text-editor\" data-id=\"cf7b01a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Aviso: No cobramos por presentar una reclamaci\u00f3n de p\u00e9rdida. Ten en cuenta que muchas empresas afirman dedicarse al servicio de objetos perdidos de la terminal 4 del aeropuerto JFK y cobran una tarifa por enviar un informe de objetos perdidos.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-788bbde learn-more-btn elementor-widget elementor-widget-html\" data-id=\"788bbde\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a style=\" background: #F7B93A!important;\" target=\"_blank\" onmouseenter=\"player70.play()\" onmouseleave=\"player70.stop()\" class=\"products-link\" href=\"https:\/\/www.chargerback.com\/ReportLostItemCBEmbed.asp?CustomerID=18594\">Presentar una reclamaci\u00f3n por objetos perdidos\n<lottie-player style=\" filter: brightness(0); \" id=\"player70\" src=\"\/wp-content\/themes\/smarte-carte\/images\/side-arrow-animation.json\" background=\"transparent\" speed=\"1\"><\/lottie-player><\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-29f47231 found jfk-found\" data-id=\"29f47231\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73a52ea9 laf-img elementor-widget elementor-widget-image\" data-id=\"73a52ea9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1785\" height=\"1366\" src=\"https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/SmarteCarte_LostFound_7238-final.jpg\" class=\"attachment-full size-full wp-image-4072\" alt=\"delivery package\" srcset=\"https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/SmarteCarte_LostFound_7238-final.jpg 1785w, https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/SmarteCarte_LostFound_7238-final-300x230.jpg 300w, https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/SmarteCarte_LostFound_7238-final-1024x784.jpg 1024w, https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/SmarteCarte_LostFound_7238-final-768x588.jpg 768w, https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/SmarteCarte_LostFound_7238-final-1536x1175.jpg 1536w\" sizes=\"(max-width: 1785px) 100vw, 1785px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b86cf1f elementor-section-content-top elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b86cf1f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6882de11 questions-data\" data-id=\"6882de11\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3e2952d elementor-section-content-top elementor-reverse-mobile question-contact elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3e2952d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7c40177 questions laf1\" data-id=\"7c40177\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6789e04 elementor-widget-tablet__width-initial laf-img1 elementor-widget elementor-widget-image\" data-id=\"6789e04\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1672\" src=\"https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/SmarteCarte_JFK_7989-final-scaled.jpg\" class=\"attachment-full size-full wp-image-4073\" alt=\"\" srcset=\"https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/SmarteCarte_JFK_7989-final-scaled.jpg 2560w, https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/SmarteCarte_JFK_7989-final-300x196.jpg 300w, https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/SmarteCarte_JFK_7989-final-1024x669.jpg 1024w, https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/SmarteCarte_JFK_7989-final-768x501.jpg 768w, https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/SmarteCarte_JFK_7989-final-1536x1003.jpg 1536w, https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/SmarteCarte_JFK_7989-final-2048x1337.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-eacc437\" data-id=\"eacc437\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8660f13 elementor-widget elementor-widget-heading\" data-id=\"8660f13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Terminal 7<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f7e01b0 calibri-regular elementor-widget elementor-widget-text-editor\" data-id=\"f7e01b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>HORARIO DE SERVICIO<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d22927a elementor-widget elementor-widget-heading\" data-id=\"d22927a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">De 6:00 a 00:00<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c9fdba7 elementor-widget elementor-widget-text-editor\" data-id=\"c9fdba7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"jfk-laf\">\n<div class=\"jfk-laf-item\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6051\" src=\"https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/12\/phone-1.svg\" alt=\"\" width=\"24\" height=\"24\" \/>+1 929-691-2066<\/div>\n<div class=\"jfk-laf-item\"><img decoding=\"async\" src=\"https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/05\/marker.svg\" \/>Terminal 7, Queens, NY 11430<\/div>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b3d50b calibri-regular elementor-widget elementor-widget-text-editor\" data-id=\"8b3d50b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Aviso: No cobramos por presentar una reclamaci\u00f3n de p\u00e9rdida. Ten en cuenta que muchas empresas afirman dedicarse al servicio de objetos perdidos de la terminal 4 del aeropuerto JFK y cobran una tarifa por enviar un informe de objetos perdidos.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5071253 learn-more-btn elementor-widget elementor-widget-html\" data-id=\"5071253\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a style=\" background: #F7B93A!important;\"target=\"_blank\" onmouseenter=\"player71.play()\" onmouseleave=\"player71.stop()\" class=\"products-link\" href=\"https:\/\/www.chargerback.com\/reportlostitemcbembed.asp?customerID=19496\">Presentar una reclamaci\u00f3n por objetos perdidos\n<lottie-player style=\" filter: brightness(0); \" id=\"player71\" src=\"\/wp-content\/themes\/smarte-carte\/images\/side-arrow-animation.json\" background=\"transparent\" speed=\"1\"><\/lottie-player>\n<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-73ca432 elementor-section-content-top elementor-reverse-mobile question-contact elementor-hidden-desktop elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"73ca432\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-27bcad6 questions\" data-id=\"27bcad6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8ab1efb elementor-widget-tablet__width-initial elementor-widget elementor-widget-image\" data-id=\"8ab1efb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1672\" src=\"https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/SmarteCarte_JFK_7989-final-scaled.jpg\" class=\"attachment-full size-full wp-image-4073\" alt=\"\" srcset=\"https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/SmarteCarte_JFK_7989-final-scaled.jpg 2560w, https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/SmarteCarte_JFK_7989-final-300x196.jpg 300w, https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/SmarteCarte_JFK_7989-final-1024x669.jpg 1024w, https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/SmarteCarte_JFK_7989-final-768x501.jpg 768w, https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/SmarteCarte_JFK_7989-final-1536x1003.jpg 1536w, https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/SmarteCarte_JFK_7989-final-2048x1337.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8a21f04 hours elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8a21f04\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-188ec83\" data-id=\"188ec83\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b50a504 calibri-regular elementor-widget elementor-widget-heading\" data-id=\"b50a504\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">HORARIO DE SERVICIO<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ff3164 calibri-regular elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"8ff3164\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Abierto todos los d\u00edas las 24 horas<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b05a151 fade-in location elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"b05a151\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"single-location\">\n<div class=\"loc-icons\">\n<div class=\"loc-icons-item\" style=\"text-align: left;\"><img decoding=\"async\" src=\"https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/05\/marker.svg\" \/><label>UBICACIONES<\/label><\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56dde2d calibri-regular elementor-widget elementor-widget-text-editor\" data-id=\"56dde2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">John F. Kennedy Airport Jamaica, New York<br style=\"display:block\">\n11430 Terminal 4 Arrivals Ground Level<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a53b2c8\" data-id=\"a53b2c8\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a5a679 elementor-widget elementor-widget-heading\" data-id=\"3a5a679\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00bfALGUNA PREGUNTA?\u00a0<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f4f49ad airport-button elementor-widget elementor-widget-html\" data-id=\"f4f49ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a onmouseenter=\"flights.play()\" onmouseleave=\"flights.stop()\" class=\"products-link\" data-toggle=\"modal\" data-target=\"#meetModal\">CONTACTA CON NOSOTROS\n<lottie-player id=\"flights\" src=\"\/wp-content\/themes\/smarte-carte\/images\/side-arrow-animation.json\" background=\"transparent\" speed=\"1\"><\/lottie-player>\n<\/a>\n\n\n\n\n<div class=\"modal fade airport-popup \" id=\"meetModal\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"meetModal\" aria-hidden=\"true\">\n  <div class=\"modal-dialog\">\n    <div class=\"modal-content\">\n      <div class=\"modal-header\">\n        <h4 class=\"modal-title\" id=\"meetModalLabel\">Contacta con nosotros<\/h4>\n        <button type=\"button\" class=\"close\" data-dismiss=\"modal\" aria-label=\"Close\">\n          <span aria-hidden=\"true\">&horarios;<\/span>\n        <\/button>\n      <\/div>\n      <div class=\"modal-body\">\n        <script charset=\"utf-8\" type=\"text\/javascript\" src=\"\/\/js.hsforms.net\/forms\/embed\/v2.js\"><\/script>\n<script>\n  hbspt.forms.create({\n    region: \"na1\",\n    portalId: \"5752400\",\n    formId: \"7ded5060-afdc-436d-a9a8-057dcc0f1e0c\"\n  });\n<\/script>\n      <\/div>\n    <\/div>\n  <\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-80794c9 airport-button elementor-widget elementor-widget-html\" data-id=\"80794c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"single-location\">\n<div class=\"loc-icons\">\n<div class=\"loc-icons-item\" style=\"text-align:left;font-weight: 400;\"><img decoding=\"async\" src=\"https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/05\/phone.svg\" \/>\u00a0<a href=\"tel:347-684-3604\">347-684-3604<\/a><\/div>\n<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41a2c66 fade-in location elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"41a2c66\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"single-location\">\n<div class=\"loc-icons\">\n<div class=\"loc-icons-item\" style=\"text-align: left;\"><img decoding=\"async\" src=\"https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/05\/marker.svg\" \/><label>UBICACIONES:<\/label><br class=\"air-loc\">Aeropuerto John F. Kennedy Airport (JFK), Terminal 4<\/div>\n<\/div>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-951e4ca calibri-regular elementor-widget elementor-widget-text-editor\" data-id=\"951e4ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Aviso: No cobramos por presentar una reclamaci\u00f3n de p\u00e9rdida. Ten en cuenta que muchas empresas afirman dedicarse al servicio de objetos<br \/> perdidos de la terminal 4 del aeropuerto JFK y cobran una tarifa por enviar un informe de objetos perdidos.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-25d7998a information-services elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"25d7998a\" data-element_type=\"section\" data-e-type=\"section\" id=\"informationService\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c575f84\" data-id=\"c575f84\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-644fc7a9 elementor-widget elementor-widget-heading\" data-id=\"644fc7a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Servicios de informaci\u00f3n\u00a0<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1aec08e0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1aec08e0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-57703d06 information-services\" data-id=\"57703d06\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8173b98 elementor-widget elementor-widget-text-editor\" data-id=\"8173b98\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div style=\"text-align: left;\">\u00bfEst\u00e1s buscando indicaciones para llegar a tu puerta de embarque, la ubicaci\u00f3n<br \/>de las salas VIP o recomendaciones para comer algo r\u00e1pido?<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4261a48 calibri-regular elementor-widget elementor-widget-text-editor\" data-id=\"4261a48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nuestro equipo de expertos est\u00e1 aqu\u00ed para responder a tus preguntas y ayudarte. Como extensi\u00f3n del aeropuerto, nos<br \/> enorgullece ayudar a los visitantes a descubrir la amplia gama de servicios y comodidades disponibles en la terminal 4 del aeropuerto JFK, garantizando un<br \/>viaje m\u00e1s agradable.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ce70ce airport-button elementor-widget-mobile__width-initial elementor-widget elementor-widget-html\" data-id=\"9ce70ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<a onmouseenter=\"info.play()\" onmouseleave=\"info.stop()\" class=\"products-link\" href=\"https:\/\/smartecarte.com\/contact\/\" data-toggle=\"modal\" data-target=\"#infoModal\">CONTACTA CON NOSOTROS\n<lottie-player id=\"info\" src=\"\/wp-content\/themes\/smarte-carte\/images\/side-arrow-animation.json\" background=\"transparent\" speed=\"1\"><\/lottie-player>\n<\/a>\n\n<div class=\"modal fade airport-popup \" id=\"infoModal\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"infoModal\" aria-hidden=\"true\">\n  <div class=\"modal-dialog\">\n    <div class=\"modal-content\">\n      <div class=\"modal-header\">\n        <h4 class=\"modal-title\" id=infoModalLabel\">Contacta con nosotros<\/h4>\n        <button type=\"button\" class=\"close\" data-dismiss=\"modal\" aria-label=\"Close\">\n          <span aria-hidden=\"true\">&horarios;<\/span>\n        <\/button>\n      <\/div>\n      <div class=\"modal-body\">\n        <script charset=\"utf-8\" type=\"text\/javascript\" src=\"\/\/js.hsforms.net\/forms\/embed\/v2.js\"><\/script>\n<script>\n  hbspt.forms.create({\n    region: \"na1\",\n    portalId: \"5752400\",\n    formId: \"7ded5060-afdc-436d-a9a8-057dcc0f1e0c\"\n  });\n<\/script>\n      <\/div>\n    <\/div>\n  <\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b7e1edb information-img\" data-id=\"b7e1edb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ccb9a19 elementor-widget elementor-widget-image\" data-id=\"4ccb9a19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"701\" src=\"https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/SmarteCarte_JFK_8398-final-935x1024.jpg\" class=\"attachment-large size-large wp-image-4074\" alt=\"\" srcset=\"https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/SmarteCarte_JFK_8398-final-935x1024.jpg 935w, https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/SmarteCarte_JFK_8398-final-274x300.jpg 274w, https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/SmarteCarte_JFK_8398-final-768x841.jpg 768w, https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/SmarteCarte_JFK_8398-final-1403x1536.jpg 1403w, https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/SmarteCarte_JFK_8398-final.jpg 1639w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Nueva York \u2013 John F. Kennedy (JFK) Deja que Smarte Carte te ayude a hacer que tus viajes por el Aeropuerto John F. Kennedy (JFK) sean f\u00e1ciles y sin estr\u00e9s con nuestros servicios para pasajeros. Smarte Carte hace que viajar por el aeropuerto JFK sea una experiencia perfecta Servicio de portaequipajes Experimenta un viaje sin [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-smarte.php","meta":{"_acf_changed":false,"content-type":"","inline_featured_image":false,"footnotes":""},"class_list":["post-6469","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>John F. Kennedy NOVEDAD - Smartecarte<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smartecarte.com\/john-f-kennedy-new\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"John F. Kennedy NOVEDAD - Smartecarte\" \/>\n<meta property=\"og:description\" content=\"Nueva York \u2013 John F. Kennedy (JFK) Deja que Smarte Carte te ayude a hacer que tus viajes por el Aeropuerto John F. Kennedy (JFK) sean f\u00e1ciles y sin estr\u00e9s con nuestros servicios para pasajeros. Smarte Carte hace que viajar por el aeropuerto JFK sea una experiencia perfecta Servicio de portaequipajes Experimenta un viaje sin [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smartecarte.com\/john-f-kennedy-new\/\" \/>\n<meta property=\"og:site_name\" content=\"Smartecarte\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-12T09:51:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/SmarteCarte_JFK_8488-final-scaled.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smartecarte.com\\\/john-f-kennedy-new\\\/\",\"url\":\"https:\\\/\\\/smartecarte.com\\\/john-f-kennedy-new\\\/\",\"name\":\"John F. Kennedy NOVEDAD - Smartecarte\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smartecarte.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smartecarte.com\\\/john-f-kennedy-new\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smartecarte.com\\\/john-f-kennedy-new\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smartecarte.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/SmarteCarte_JFK_8488-final-scaled.jpg\",\"datePublished\":\"2024-01-23T09:01:44+00:00\",\"dateModified\":\"2024-03-12T09:51:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smartecarte.com\\\/john-f-kennedy-new\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smartecarte.com\\\/john-f-kennedy-new\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/smartecarte.com\\\/john-f-kennedy-new\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smartecarte.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/SmarteCarte_JFK_8488-final-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/smartecarte.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/SmarteCarte_JFK_8488-final-scaled.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smartecarte.com\\\/john-f-kennedy-new\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/smartecarte.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"John F. Kennedy NOVEDAD\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smartecarte.com\\\/#website\",\"url\":\"https:\\\/\\\/smartecarte.com\\\/\",\"name\":\"Smartecarte\",\"description\":\"Transforming Travel and Leisure Worldwide\",\"publisher\":{\"@id\":\"https:\\\/\\\/smartecarte.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smartecarte.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/smartecarte.com\\\/#organization\",\"name\":\"Smartecarte\",\"url\":\"https:\\\/\\\/smartecarte.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/smartecarte.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/smartecarte.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Logo-5-1.png\",\"contentUrl\":\"https:\\\/\\\/smartecarte.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Logo-5-1.png\",\"width\":300,\"height\":48,\"caption\":\"Smartecarte\"},\"image\":{\"@id\":\"https:\\\/\\\/smartecarte.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"John F. Kennedy NOVEDAD - Smartecarte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smartecarte.com\/john-f-kennedy-new\/","og_locale":"es_ES","og_type":"article","og_title":"John F. Kennedy NOVEDAD - Smartecarte","og_description":"Nueva York \u2013 John F. Kennedy (JFK) Deja que Smarte Carte te ayude a hacer que tus viajes por el Aeropuerto John F. Kennedy (JFK) sean f\u00e1ciles y sin estr\u00e9s con nuestros servicios para pasajeros. Smarte Carte hace que viajar por el aeropuerto JFK sea una experiencia perfecta Servicio de portaequipajes Experimenta un viaje sin [&hellip;]","og_url":"https:\/\/smartecarte.com\/john-f-kennedy-new\/","og_site_name":"Smartecarte","article_modified_time":"2024-03-12T09:51:50+00:00","og_image":[{"url":"https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/SmarteCarte_JFK_8488-final-scaled.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/smartecarte.com\/john-f-kennedy-new\/","url":"https:\/\/smartecarte.com\/john-f-kennedy-new\/","name":"John F. Kennedy NOVEDAD - Smartecarte","isPartOf":{"@id":"https:\/\/smartecarte.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smartecarte.com\/john-f-kennedy-new\/#primaryimage"},"image":{"@id":"https:\/\/smartecarte.com\/john-f-kennedy-new\/#primaryimage"},"thumbnailUrl":"https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/SmarteCarte_JFK_8488-final-scaled.jpg","datePublished":"2024-01-23T09:01:44+00:00","dateModified":"2024-03-12T09:51:50+00:00","breadcrumb":{"@id":"https:\/\/smartecarte.com\/john-f-kennedy-new\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smartecarte.com\/john-f-kennedy-new\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/smartecarte.com\/john-f-kennedy-new\/#primaryimage","url":"https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/SmarteCarte_JFK_8488-final-scaled.jpg","contentUrl":"https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/07\/SmarteCarte_JFK_8488-final-scaled.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/smartecarte.com\/john-f-kennedy-new\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smartecarte.com\/"},{"@type":"ListItem","position":2,"name":"John F. Kennedy NOVEDAD"}]},{"@type":"WebSite","@id":"https:\/\/smartecarte.com\/#website","url":"https:\/\/smartecarte.com\/","name":"Smartecarte","description":"Transforming Travel and Leisure Worldwide","publisher":{"@id":"https:\/\/smartecarte.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smartecarte.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/smartecarte.com\/#organization","name":"Smartecarte","url":"https:\/\/smartecarte.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/smartecarte.com\/#\/schema\/logo\/image\/","url":"https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/04\/Logo-5-1.png","contentUrl":"https:\/\/smartecarte.com\/wp-content\/uploads\/2023\/04\/Logo-5-1.png","width":300,"height":48,"caption":"Smartecarte"},"image":{"@id":"https:\/\/smartecarte.com\/#\/schema\/logo\/image\/"}}]}},"featured_image_src":null,"featured_image_src_square":null,"_links":{"self":[{"href":"https:\/\/smartecarte.com\/es\/wp-json\/wp\/v2\/pages\/6469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smartecarte.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/smartecarte.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/smartecarte.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smartecarte.com\/es\/wp-json\/wp\/v2\/comments?post=6469"}],"version-history":[{"count":0,"href":"https:\/\/smartecarte.com\/es\/wp-json\/wp\/v2\/pages\/6469\/revisions"}],"wp:attachment":[{"href":"https:\/\/smartecarte.com\/es\/wp-json\/wp\/v2\/media?parent=6469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}